{"id":1872076,"date":"2024-04-12T06:47:06","date_gmt":"2025-01-10T12:05:28","guid":{"rendered":"https:\/\/www.timetobackpack.com\/shop\/uncategorized\/spank-me-2-days-2-nights-sailing-whitsundays\/"},"modified":"2025-03-19T20:35:26","modified_gmt":"2025-03-19T19:35:26","slug":"spank-me-2-days-2-nights-sailing-whitsundays","status":"publish","type":"product","link":"https:\/\/www.timetobackpack.com\/en\/shop\/east-coast\/whitsundays-en\/spank-me-2-days-2-nights-sailing-whitsundays\/","title":{"rendered":"Spank Me 2 days \/ 2 nights sailing Whitsundays"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;0&#8243; bottom_padding=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;tourmenu&#8221; id=&#8221;tourmenu&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][page_submenu alignment=&#8221;center&#8221; sticky=&#8221;true&#8221; bg_color=&#8221;#2b2b2b&#8221; link_color=&#8221;#ffffff&#8221;][page_link title=&#8221;Book&#8221; id=&#8221;1712898085571-10&#8243; tab_id=&#8221;1712898085571-8&#8243; link_url=&#8221;#buchen&#8221;][\/page_link][page_link title=&#8221;Pictures&#8221; id=&#8221;1712898085635-1&#8243; tab_id=&#8221;1712898085636-0&#8243; link_url=&#8221;#galerie&#8221;][\/page_link][page_link link_url=&#8221;#highlights&#8221; title=&#8221;Highlights&#8221; id=&#8221;1712898085656-6&#8243; tab_id=&#8221;1712898085657-2&#8243;][vc_column_text][\/vc_column_text][\/page_link][page_link link_url=&#8221;#route&#8221; title=&#8221;Route&#8221; id=&#8221;1712898085686-0&#8243; tab_id=&#8221;1712898085687-3&#8243;][vc_column_text][\/vc_column_text][\/page_link][page_link title=&#8221;Included&#8221; id=&#8221;1712898085710-6&#8243; tab_id=&#8221;1712898085712-10&#8243; link_url=&#8221;#inklusive&#8221;][\/page_link][page_link title=&#8221;Travel information&#8221; id=&#8221;1712898085733-7&#8243; tab_id=&#8221;1712898085734-6&#8243; link_url=&#8221;#reiseinfos&#8221;][\/page_link][page_link title=&#8221;Extras&#8221; id=&#8221;1712898085751-0&#8243; tab_id=&#8221;1712898085752-0&#8243; link_url=&#8221;#extras&#8221;][\/page_link][page_link title=&#8221;Group size&#8221; id=&#8221;1712898085772-10&#8243; tab_id=&#8221;1712898085773-7&#8243; link_url=&#8221;#gruppengroesse&#8221;][\/page_link][page_link title=&#8221;Bring along&#8221; id=&#8221;1712898085795-5&#8243; tab_id=&#8221;1712898085797-0&#8243; link_url=&#8221;#mitbringen&#8221;][\/page_link][page_link title=&#8221;Map&#8221; id=&#8221;1712898085818-4&#8243; tab_id=&#8221;1712898085819-5&#8243; link_url=&#8221;#karte&#8221;][\/page_link][page_link title=&#8221;Contact us&#8221; id=&#8221;1712898085841-7&#8243; tab_id=&#8221;1712898085842-7&#8243; link_url=&#8221;#kontakt&#8221;][\/page_link][\/page_submenu][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;highlights&#8221; id=&#8221;highlights&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-star accent-color\"><\/i> <\/div><div class=\"iwt-text\"> \n<h2>HIGHLIGHTS<\/h2>\n<p>Whitsundays sailing <\/div><div class=\"clear\"><\/div><\/div>[vc_column_text]Spank Me Whitsundays offers space for guests of all ages. She can accommodate 27 guests and 3 crew members in open dormitories with single and double beds. Sail around the Whitsundays and catch a glimpse of a breathtaking variety of marine life during fascinating daily snorkeling excursions. Explore the World Heritage-listed Whitsunday Islands, visit Whitehaven Beach and snorkel along the Great Barrier Reef. Help the crew set the mainsail and anchor at each exciting destination. Alternatively, relax on the spacious deck and enjoy the views of the pristine Whitsunday Islands. Each evening, help the crew prepare delicious specialties such as beef tacos, spaghetti bolognese, healthy ham and beef salad wraps, continental breakfasts, fresh bread, green salad, pasta salads and much more. You won&#8217;t go hungry! Or position yourself at the bow of the ship, where you can watch the sky change from buttery yellow to flaming magenta as the sun disappears below the horizon. The 2-day, 2-night Whitsundays sailing tour with Spank Me through the Whitsundays can include Whitehaven Beach, Hook Island, Hayman Island, Border Island and Whitsunday Island, with snorkeling stops at Luncheon Bay, Caves Cove, Blue Pearl Bay and many other great spots. Snorkeling equipment and all stinger suits\/diving suits are included in the price.[\/vc_column_text][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; class=&#8221;route&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; el_id=&#8221;route&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-ship accent-color\"><\/i> <\/div><div class=\"iwt-text\"> \n<h2>ROUTE<\/h2>\n<p>Whitsundays sailing <\/div><div class=\"clear\"><\/div><\/div><div class=\"nectar-fancy-ul\" data-list-icon=\"linecon-icon-location\" data-animation=\"false\" data-animation-delay=\"0\" data-color=\"accent-color\" data-spacing=\"default\" data-alignment=\"left\"> \n<ul>\n<li><a href=\"https:\/\/www.queensland.com\/au\/en\/things-to-do\/attractions\/p-56b25dc07b935fbe730dc52c-whitehaven-beach\" target=\"_blank\" rel=\"noopener\">Whitehaven Beach<\/a><\/li>\n<li>Hook Island<\/li>\n<li>Hayman Island<\/li>\n<li>Border Island<\/li>\n<li><span style=\"color: #333333\"><a style=\"color: #333333\" href=\"https:\/\/www.timetobackpack.com\/en\/whitsundays\/\" target=\"_blank\" rel=\"noopener\">Whitsundays Island<\/a><\/span><\/li>\n<li>Snorkeling stops in Luncheon Bay, Caves Cove, Blue Pearl Bay and many other fantastic places.<\/li>\n<\/ul>\n <\/div>[\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; class=&#8221;inklusive&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; el_id=&#8221;inklusive&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-compress accent-color\"><\/i> <\/div><div class=\"iwt-text\"> \n<h2>INCLUSIVE<\/h2>\n<p>What is included <\/div><div class=\"clear\"><\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"nectar-fancy-ul\" data-list-icon=\"fa fa-check\" data-animation=\"false\" data-animation-delay=\"0\" data-color=\"accent-color\" data-spacing=\"default\" data-alignment=\"left\"> \n<ul>\n<li>Snorkeling equipment and instruction<\/li>\n<li>Wetsuit<\/li>\n<li>All meals included. Snacks<\/li>\n<li>Coffee, tea and tap water<\/li>\n<li>Bed linen<\/li>\n<li>All marine and national park fees<\/li>\n<li>legendary fun crew<\/li>\n<\/ul>\n <\/div>[\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; class=&#8221;reiseinfos&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; el_id=&#8221;reiseinfos&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-hourglass-half accent-color\"><\/i> <\/div><div class=\"iwt-text\"> \n<h2>TRAVEL INFO<\/h2>\n<p>Everything you need to know <\/div><div class=\"clear\"><\/div><\/div>[vc_column_text]<strong>Start:<\/strong> Airlie Beach: Every Sunday, Wednesday, Friday.<br \/>\n<strong>Meeting point:<\/strong> Meeting point C, Coral Sea Marina, Airlie Beach, under the sunshades on the right-hand side of the two buildings.<br \/>\n<strong>End:<\/strong> In Airlie Beach:[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; class=&#8221;extras&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; el_id=&#8221;extras&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-plus-square accent-color\"><\/i> <\/div><div class=\"iwt-text\"> \n<h2>EXTRAS<\/h2>\n <\/div><div class=\"clear\"><\/div><\/div>[vc_column_text]Not included &#8211; alcohol, snacks (potato chips, chocolate, cola etc.) If you bring alcohol, please make sure that you do not bring glass bottles or red wine.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; class=&#8221;gruppengroesse&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; el_id=&#8221;gruppengroesse&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-users accent-color\"><\/i> <\/div><div class=\"iwt-text\"> \n<h2>GROUP SIZE<\/h2>\n<p>For how many people is this Whitsundays tour suitable <\/div><div class=\"clear\"><\/div><\/div>[vc_column_text]27 people and 3 crew members[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; class=&#8221;mitbringen&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; el_id=&#8221;mitbringen&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-suitcase accent-color\"><\/i> <\/div><div class=\"iwt-text\"> \n<h2>BRING WITH YOU<\/h2>\n<p>What you should bring with you <\/div><div class=\"clear\"><\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_flip_box image_url_1=&#8221;279&#8243; bg_color=&#8221;#ededed&#8221; text_color=&#8221;light&#8221; icon_color=&#8221;Accent-Color&#8221; image_url_2=&#8221;279&#8243; bg_color_2=&#8221;#3a3a3a&#8221; text_color_2=&#8221;dark&#8221; h_text_align=&#8221;center&#8221; v_text_align=&#8221;center&#8221; image_loading=&#8221;default&#8221; flip_direction=&#8221;horizontal-to-left&#8221; min_height=&#8221;200&#8243;]Small bag[\/nectar_flip_box][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_flip_box image_url_1=&#8221;256&#8243; bg_color=&#8221;#ededed&#8221; text_color=&#8221;light&#8221; icon_color=&#8221;Accent-Color&#8221; image_url_2=&#8221;256&#8243; bg_color_2=&#8221;#3a3a3a&#8221; text_color_2=&#8221;dark&#8221; h_text_align=&#8221;center&#8221; v_text_align=&#8221;center&#8221; image_loading=&#8221;default&#8221; flip_direction=&#8221;horizontal-to-left&#8221; min_height=&#8221;200&#8243;]Swimwear[\/nectar_flip_box][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_flip_box image_url_1=&#8221;282&#8243; bg_color=&#8221;#ededed&#8221; text_color=&#8221;light&#8221; icon_color=&#8221;Accent-Color&#8221; image_url_2=&#8221;282&#8243; bg_color_2=&#8221;#3a3a3a&#8221; text_color_2=&#8221;dark&#8221; h_text_align=&#8221;center&#8221; v_text_align=&#8221;center&#8221; image_loading=&#8221;default&#8221; flip_direction=&#8221;horizontal-to-left&#8221; min_height=&#8221;200&#8243;]Towel[\/nectar_flip_box][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_flip_box image_url_1=&#8221;280&#8243; bg_color=&#8221;#ededed&#8221; text_color=&#8221;light&#8221; icon_color=&#8221;Accent-Color&#8221; image_url_2=&#8221;280&#8243; bg_color_2=&#8221;#3a3a3a&#8221; text_color_2=&#8221;dark&#8221; h_text_align=&#8221;center&#8221; v_text_align=&#8221;center&#8221; image_loading=&#8221;default&#8221; flip_direction=&#8221;horizontal-to-left&#8221; min_height=&#8221;200&#8243;]Sun protection[\/nectar_flip_box][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_flip_box image_url_1=&#8221;270&#8243; bg_color=&#8221;#ededed&#8221; text_color=&#8221;light&#8221; icon_color=&#8221;Accent-Color&#8221; image_url_2=&#8221;270&#8243; bg_color_2=&#8221;#3a3a3a&#8221; text_color_2=&#8221;dark&#8221; h_text_align=&#8221;center&#8221; v_text_align=&#8221;center&#8221; image_loading=&#8221;default&#8221; flip_direction=&#8221;horizontal-to-left&#8221; min_height=&#8221;200&#8243;]Headgear[\/nectar_flip_box][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_flip_box image_url_1=&#8221;257&#8243; bg_color=&#8221;#ededed&#8221; text_color=&#8221;light&#8221; icon_color=&#8221;Accent-Color&#8221; image_url_2=&#8221;257&#8243; bg_color_2=&#8221;#3a3a3a&#8221; text_color_2=&#8221;dark&#8221; h_text_align=&#8221;center&#8221; v_text_align=&#8221;center&#8221; image_loading=&#8221;default&#8221; flip_direction=&#8221;horizontal-to-left&#8221; min_height=&#8221;200&#8243;]Camera[\/nectar_flip_box][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_flip_box image_url_1=&#8221;278&#8243; bg_color=&#8221;#ededed&#8221; text_color=&#8221;light&#8221; icon_color=&#8221;Accent-Color&#8221; image_url_2=&#8221;278&#8243; bg_color_2=&#8221;#3a3a3a&#8221; text_color_2=&#8221;dark&#8221; h_text_align=&#8221;center&#8221; v_text_align=&#8221;center&#8221; image_loading=&#8221;default&#8221; flip_direction=&#8221;horizontal-to-left&#8221; min_height=&#8221;200&#8243;]Insect protection[\/nectar_flip_box][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_flip_box image_url_1=&#8221;268&#8243; bg_color=&#8221;#ededed&#8221; text_color=&#8221;light&#8221; icon_color=&#8221;Accent-Color&#8221; image_url_2=&#8221;268&#8243; bg_color_2=&#8221;#3a3a3a&#8221; text_color_2=&#8221;dark&#8221; h_text_align=&#8221;center&#8221; v_text_align=&#8221;center&#8221; image_loading=&#8221;default&#8221; flip_direction=&#8221;horizontal-to-left&#8221; min_height=&#8221;200&#8243;]warm clothing[\/nectar_flip_box][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_flip_box image_url_1=&#8221;272&#8243; bg_color=&#8221;#ededed&#8221; text_color=&#8221;light&#8221; icon_color=&#8221;Accent-Color&#8221; image_url_2=&#8221;272&#8243; bg_color_2=&#8221;#3a3a3a&#8221; text_color_2=&#8221;dark&#8221; h_text_align=&#8221;center&#8221; v_text_align=&#8221;center&#8221; image_loading=&#8221;default&#8221; flip_direction=&#8221;horizontal-to-left&#8221; min_height=&#8221;200&#8243;]Travel tablets[\/nectar_flip_box][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; class=&#8221;karte&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; el_id=&#8221;karte&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-map accent-color\"><\/i> <\/div><div class=\"iwt-text\"> \n<h2>CARD<\/h2>\n<p>Where exactly is it going <\/div><div class=\"clear\"><\/div><\/div>[nectar_gmap map_type=&#8221;google&#8221; zoom=&#8221;5&#8243; enable_zoom=&#8221;1&#8243; marker_style=&#8221;default&#8221; nectar_marker_color=&#8221;accent-color&#8221; marker_image=&#8221;285&#8243; marker_animation=&#8221;1&#8243; size=&#8221;600&#8243; map_center_lat=&#8221;-20.186242&#8243; map_center_lng=&#8221;148.726855&#8243; map_markers=&#8221;-20.186242|148.726855|&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; class=&#8221;kontakt&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; el_id=&#8221;kontakt&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-envelope-o accent-color\"><\/i> <\/div><div class=\"iwt-text\"> \n<h2>CONTACT<\/h2>\n<p>Do you have any questions? <\/div><div class=\"clear\"><\/div><\/div>\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1873297-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"1873297\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/product\/1872076#wpcf7-f1873297-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"1873297\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.1\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1873297-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7cf_hidden_group_fields\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_hidden_groups\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_visible_groups\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_repeaters\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_steps\" value=\"{}\" \/><input type=\"hidden\" name=\"_wpcf7cf_options\" value=\"{&quot;form_id&quot;:1873297,&quot;conditions&quot;:[],&quot;settings&quot;:{&quot;animation&quot;:&quot;yes&quot;,&quot;animation_intime&quot;:200,&quot;animation_outtime&quot;:200,&quot;conditions_ui&quot;:&quot;normal&quot;,&quot;notice_dismissed&quot;:false,&quot;notice_dismissed_rollback-cf7-5.3.2&quot;:true,&quot;notice_dismissed_rollback-cf7-5.6&quot;:true,&quot;notice_dismissed_rollback-cf7-5.8.1&quot;:true}}\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"vorname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Name\" value=\"\" type=\"text\" name=\"vorname\" \/><\/span><\/label><br \/>\n<label><span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"email\" value=\"\" type=\"email\" name=\"email\" \/><\/span><\/label><br \/>\n<label><span class=\"wpcf7-form-control-wrap\" data-name=\"telefon\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Telephone\" value=\"\" type=\"text\" name=\"telefon\" \/><\/span><\/label><br \/>\n<label><span class=\"wpcf7-form-control-wrap\" data-name=\"nachricht\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Your message\" name=\"nachricht\"><\/textarea><\/span><\/label><br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Submit\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; class=&#8221;weiteretouren&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; el_id=&#8221;weiteretouren&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-search accent-color\"><\/i> <\/div><div class=\"iwt-text\"> \n<h2>FURTHER TOURS<\/h2>\n<p>You might also like these tours! <\/div><div class=\"clear\"><\/div><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>Discover a treasure trove of natural wonders during a 2-day, 2-night sailing adventure aboard Spank Me, an 82-foot former racing yacht.<\/p>\n","protected":false},"featured_media":1872086,"template":"","meta":{"_monsterinsights_skip_tracking":false},"product_brand":[],"product_cat":[280,69],"product_tag":[],"class_list":{"0":"post-1872076","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-booking-by-hero-en","7":"product_cat-whitsundays-en","9":"first","10":"instock","11":"virtual","12":"sold-individually","13":"taxable","14":"purchasable","15":"product-type-booking"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Spank Me 2 days 2 nights Whitsundays sailing<\/title>\n<meta name=\"description\" content=\"Whitsundays: Experience a wealth of natural treasures during a 2-day sailing adventure aboard Spank Me, an 82-foot former racing yacht.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.timetobackpack.com\/en\/shop\/east-coast\/whitsundays-en\/spank-me-2-days-2-nights-sailing-whitsundays\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spank Me 2 days 2 nights Whitsundays sailing\" \/>\n<meta property=\"og:description\" content=\"Whitsundays: Experience a wealth of natural treasures during a 2-day sailing adventure aboard Spank Me, an 82-foot former racing yacht.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.timetobackpack.com\/en\/shop\/east-coast\/whitsundays-en\/spank-me-2-days-2-nights-sailing-whitsundays\/\" \/>\n<meta property=\"og:site_name\" content=\"Time To Backpack\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/timetobackpack\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-19T19:35:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/timetobackpack.com\/wp-content\/uploads\/2017\/09\/Whitsunday-Adventurer-Sailing-the-Whitsundays_1170PX-wide.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.timetobackpack.com\/en\/shop\/east-coast\/whitsundays-en\/spank-me-2-days-2-nights-sailing-whitsundays\/\",\"url\":\"https:\/\/www.timetobackpack.com\/en\/shop\/east-coast\/whitsundays-en\/spank-me-2-days-2-nights-sailing-whitsundays\/\",\"name\":\"Spank Me 2 days 2 nights Whitsundays sailing\",\"isPartOf\":{\"@id\":\"https:\/\/www.timetobackpack.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.timetobackpack.com\/en\/shop\/east-coast\/whitsundays-en\/spank-me-2-days-2-nights-sailing-whitsundays\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.timetobackpack.com\/en\/shop\/east-coast\/whitsundays-en\/spank-me-2-days-2-nights-sailing-whitsundays\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.timetobackpack.com\/wp-content\/uploads\/2024\/04\/spank-me-2.jpg\",\"datePublished\":\"2025-01-10T12:05:28+00:00\",\"dateModified\":\"2025-03-19T19:35:26+00:00\",\"description\":\"Whitsundays: Experience a wealth of natural treasures during a 2-day sailing adventure aboard Spank Me, an 82-foot former racing yacht.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.timetobackpack.com\/en\/shop\/east-coast\/whitsundays-en\/spank-me-2-days-2-nights-sailing-whitsundays\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.timetobackpack.com\/en\/shop\/east-coast\/whitsundays-en\/spank-me-2-days-2-nights-sailing-whitsundays\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.timetobackpack.com\/en\/shop\/east-coast\/whitsundays-en\/spank-me-2-days-2-nights-sailing-whitsundays\/#primaryimage\",\"url\":\"https:\/\/www.timetobackpack.com\/wp-content\/uploads\/2024\/04\/spank-me-2.jpg\",\"contentUrl\":\"https:\/\/www.timetobackpack.com\/wp-content\/uploads\/2024\/04\/spank-me-2.jpg\",\"width\":1500,\"height\":789},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.timetobackpack.com\/en\/shop\/east-coast\/whitsundays-en\/spank-me-2-days-2-nights-sailing-whitsundays\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.timetobackpack.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.timetobackpack.com\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Spank Me 2 days \/ 2 nights sailing Whitsundays\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.timetobackpack.com\/en\/#website\",\"url\":\"https:\/\/www.timetobackpack.com\/en\/\",\"name\":\"Time To Backpack\",\"description\":\"Willkomen bei Time To Backpack\",\"publisher\":{\"@id\":\"https:\/\/www.timetobackpack.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.timetobackpack.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.timetobackpack.com\/en\/#organization\",\"name\":\"Time To Backpack\",\"url\":\"https:\/\/www.timetobackpack.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.timetobackpack.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/timetobackpack.com\/wp-content\/uploads\/2017\/12\/final_logo-copy.jpg\",\"contentUrl\":\"https:\/\/timetobackpack.com\/wp-content\/uploads\/2017\/12\/final_logo-copy.jpg\",\"width\":1248,\"height\":1211,\"caption\":\"Time To Backpack\"},\"image\":{\"@id\":\"https:\/\/www.timetobackpack.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/timetobackpack\/\",\"https:\/\/www.instagram.com\/timetobackpack\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Spank Me 2 days 2 nights Whitsundays sailing","description":"Whitsundays: Experience a wealth of natural treasures during a 2-day sailing adventure aboard Spank Me, an 82-foot former racing yacht.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.timetobackpack.com\/en\/shop\/east-coast\/whitsundays-en\/spank-me-2-days-2-nights-sailing-whitsundays\/","og_locale":"en_US","og_type":"article","og_title":"Spank Me 2 days 2 nights Whitsundays sailing","og_description":"Whitsundays: Experience a wealth of natural treasures during a 2-day sailing adventure aboard Spank Me, an 82-foot former racing yacht.","og_url":"https:\/\/www.timetobackpack.com\/en\/shop\/east-coast\/whitsundays-en\/spank-me-2-days-2-nights-sailing-whitsundays\/","og_site_name":"Time To Backpack","article_publisher":"https:\/\/www.facebook.com\/timetobackpack\/","article_modified_time":"2025-03-19T19:35:26+00:00","og_image":[{"url":"https:\/\/timetobackpack.com\/wp-content\/uploads\/2017\/09\/Whitsunday-Adventurer-Sailing-the-Whitsundays_1170PX-wide.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.timetobackpack.com\/en\/shop\/east-coast\/whitsundays-en\/spank-me-2-days-2-nights-sailing-whitsundays\/","url":"https:\/\/www.timetobackpack.com\/en\/shop\/east-coast\/whitsundays-en\/spank-me-2-days-2-nights-sailing-whitsundays\/","name":"Spank Me 2 days 2 nights Whitsundays sailing","isPartOf":{"@id":"https:\/\/www.timetobackpack.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.timetobackpack.com\/en\/shop\/east-coast\/whitsundays-en\/spank-me-2-days-2-nights-sailing-whitsundays\/#primaryimage"},"image":{"@id":"https:\/\/www.timetobackpack.com\/en\/shop\/east-coast\/whitsundays-en\/spank-me-2-days-2-nights-sailing-whitsundays\/#primaryimage"},"thumbnailUrl":"https:\/\/www.timetobackpack.com\/wp-content\/uploads\/2024\/04\/spank-me-2.jpg","datePublished":"2025-01-10T12:05:28+00:00","dateModified":"2025-03-19T19:35:26+00:00","description":"Whitsundays: Experience a wealth of natural treasures during a 2-day sailing adventure aboard Spank Me, an 82-foot former racing yacht.","breadcrumb":{"@id":"https:\/\/www.timetobackpack.com\/en\/shop\/east-coast\/whitsundays-en\/spank-me-2-days-2-nights-sailing-whitsundays\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.timetobackpack.com\/en\/shop\/east-coast\/whitsundays-en\/spank-me-2-days-2-nights-sailing-whitsundays\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.timetobackpack.com\/en\/shop\/east-coast\/whitsundays-en\/spank-me-2-days-2-nights-sailing-whitsundays\/#primaryimage","url":"https:\/\/www.timetobackpack.com\/wp-content\/uploads\/2024\/04\/spank-me-2.jpg","contentUrl":"https:\/\/www.timetobackpack.com\/wp-content\/uploads\/2024\/04\/spank-me-2.jpg","width":1500,"height":789},{"@type":"BreadcrumbList","@id":"https:\/\/www.timetobackpack.com\/en\/shop\/east-coast\/whitsundays-en\/spank-me-2-days-2-nights-sailing-whitsundays\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.timetobackpack.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.timetobackpack.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Spank Me 2 days \/ 2 nights sailing Whitsundays"}]},{"@type":"WebSite","@id":"https:\/\/www.timetobackpack.com\/en\/#website","url":"https:\/\/www.timetobackpack.com\/en\/","name":"Time To Backpack","description":"Willkomen bei Time To Backpack","publisher":{"@id":"https:\/\/www.timetobackpack.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.timetobackpack.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.timetobackpack.com\/en\/#organization","name":"Time To Backpack","url":"https:\/\/www.timetobackpack.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.timetobackpack.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/timetobackpack.com\/wp-content\/uploads\/2017\/12\/final_logo-copy.jpg","contentUrl":"https:\/\/timetobackpack.com\/wp-content\/uploads\/2017\/12\/final_logo-copy.jpg","width":1248,"height":1211,"caption":"Time To Backpack"},"image":{"@id":"https:\/\/www.timetobackpack.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/timetobackpack\/","https:\/\/www.instagram.com\/timetobackpack\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.timetobackpack.com\/en\/wp-json\/wp\/v2\/product\/1872076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.timetobackpack.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.timetobackpack.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.timetobackpack.com\/en\/wp-json\/wp\/v2\/media\/1872086"}],"wp:attachment":[{"href":"https:\/\/www.timetobackpack.com\/en\/wp-json\/wp\/v2\/media?parent=1872076"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.timetobackpack.com\/en\/wp-json\/wp\/v2\/product_brand?post=1872076"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.timetobackpack.com\/en\/wp-json\/wp\/v2\/product_cat?post=1872076"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.timetobackpack.com\/en\/wp-json\/wp\/v2\/product_tag?post=1872076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}